{"id":69878,"date":"2026-03-22T11:31:09","date_gmt":"2026-03-22T15:31:09","guid":{"rendered":"https:\/\/nysino.com\/am1480\/?page_id=69878"},"modified":"2026-03-22T11:37:54","modified_gmt":"2026-03-22T15:37:54","slug":"classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89","status":"publish","type":"page","link":"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/","title":{"rendered":"Classic 25 \u56de\u5473\u597d\u6b4c25\u8f09"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"69878\" class=\"elementor elementor-69878\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-440986d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"440986d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5932d61\" data-id=\"5932d61\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26df52c elementor-widget elementor-widget-image\" data-id=\"26df52c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"576\" src=\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/Classic-25-\u56de\u5473\u597d\u6b4c25\u8f09-\u4e3b\u6301-\u6587\u6d69-1024x576.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/Classic-25-\u56de\u5473\u597d\u6b4c25\u8f09-\u4e3b\u6301-\u6587\u6d69-1024x576.png 1024w, https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/Classic-25-\u56de\u5473\u597d\u6b4c25\u8f09-\u4e3b\u6301-\u6587\u6d69-300x169.png 300w, https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/Classic-25-\u56de\u5473\u597d\u6b4c25\u8f09-\u4e3b\u6301-\u6587\u6d69-768x432.png 768w, https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/Classic-25-\u56de\u5473\u597d\u6b4c25\u8f09-\u4e3b\u6301-\u6587\u6d69-1536x864.png 1536w, https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/Classic-25-\u56de\u5473\u597d\u6b4c25\u8f09-\u4e3b\u6301-\u6587\u6d69.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d6a69e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6a69e5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de3e6e9\" data-id=\"de3e6e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d55af1 elementor-widget elementor-widget-text-editor\" data-id=\"4d55af1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\n\t<div id=\"wpbaw-blog-1\" class=\"blogfree-plugin blog-clearfix \">\n\t\n\t\t\t\t<div id=\"post-70990\" class=\"blog type-blog blog-clearfix wpbaw-blog-class blog-col-2 wpbaw-first has-no-date no-thumb\">\n\t\t\t<div class=\"blog-inner-wrap-view blog-clearfix\">\n\t\t\t\t\n\t\t\t\t<div class=\"blog-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"post-content-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"blog-title\"><a href=\"https:\/\/nysino.com\/am1480\/blog-post\/%e3%8b%84%e3%8f%a6-2026-1800-1900-am1480-25%e9%80%b1%e5%b9%b4%e5%8f%b0%e6%85%b6%e7%89%b9%e5%82%99%e7%af%80%e7%9b%ae%e3%80%8aclassic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c%e5%bb%bf\/\" rel=\"bookmark\">\u32c4\u33e6 2026 18:00-19:00 AM1480 25\u9031\u5e74\u53f0\u6176\u7279\u5099\u7bc0\u76ee\u300aClassic 25 \u2013 \u56de\u5473\u597d\u6b4c\u5eff\u4e94\u8f09&#128252;\u300bEP9 \u4e3b\u6301\uff1a\u6587\u6d69<\/a><\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"blog-content-excerpt\">\n\t\t\t\t\t\t\t<!-- wp:audio {\"id\":70994} -->\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/05\/2026.05.07-18.00.00-D.mp3\"><\/audio><\/figure>\n<!-- \/wp:audio -->\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div id=\"post-70844\" class=\"blog type-blog blog-clearfix wpbaw-blog-class blog-col-2 has-no-date no-thumb\">\n\t\t\t<div class=\"blog-inner-wrap-view blog-clearfix\">\n\t\t\t\t\n\t\t\t\t<div class=\"blog-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"post-content-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"blog-title\"><a href=\"https:\/\/nysino.com\/am1480\/blog-post\/%e3%8b%83%e3%8f%bd-2026-1800-1900-am1480-25%e9%80%b1%e5%b9%b4%e5%8f%b0%e6%85%b6%e7%89%b9%e5%82%99%e7%af%80%e7%9b%ae%e3%80%8aclassic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c%e5%bb%bf\/\" rel=\"bookmark\">\u32c3\u33fd 2026 18:00-19:00 AM1480 25\u9031\u5e74\u53f0\u6176\u7279\u5099\u7bc0\u76ee\u300aClassic 25 \u2013 \u56de\u5473\u597d\u6b4c\u5eff\u4e94\u8f09&#128252;\u300bEP8 \u4e3b\u6301\uff1a\u6587\u6d69<\/a><\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"blog-content-excerpt\">\n\t\t\t\t\t\t\t<!-- wp:audio {\"id\":70845} -->\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/04\/2026.04.30-18.00.00-D.mp3\"><\/audio><\/figure>\n<!-- \/wp:audio -->\n\n<!-- wp:paragraph -->\n<p><audio src=\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/04\/2026.04.23-18.00.00-D.mp3\"><\/audio><\/p>\n<!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div id=\"post-70702\" class=\"blog type-blog blog-clearfix wpbaw-blog-class blog-col-2 wpbaw-first has-no-date no-thumb\">\n\t\t\t<div class=\"blog-inner-wrap-view blog-clearfix\">\n\t\t\t\t\n\t\t\t\t<div class=\"blog-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"post-content-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"blog-title\"><a href=\"https:\/\/nysino.com\/am1480\/blog-post\/%e3%8b%83%e3%8f%b6-2026-1800-1900-am1480-25%e9%80%b1%e5%b9%b4%e5%8f%b0%e6%85%b6%e7%89%b9%e5%82%99%e7%af%80%e7%9b%ae%e3%80%8aclassic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c%e5%bb%bf\/\" rel=\"bookmark\">\u32c3\u33f6 2026 18:00-19:00 AM1480 25\u9031\u5e74\u53f0\u6176\u7279\u5099\u7bc0\u76ee\u300aClassic 25 \u2013 \u56de\u5473\u597d\u6b4c\u5eff\u4e94\u8f09&#128252;\u300bEP7 \u4e3b\u6301\uff1a\u6587\u6d69<\/a><\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"blog-content-excerpt\">\n\t\t\t\t\t\t\t<!-- wp:audio {\"id\":70703} -->\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/04\/2026.04.23-18.00.00-D.mp3\"><\/audio><\/figure>\n<!-- \/wp:audio -->\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div id=\"post-70509\" class=\"blog type-blog blog-clearfix wpbaw-blog-class blog-col-2 has-no-date no-thumb\">\n\t\t\t<div class=\"blog-inner-wrap-view blog-clearfix\">\n\t\t\t\t\n\t\t\t\t<div class=\"blog-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"post-content-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"blog-title\"><a href=\"https:\/\/nysino.com\/am1480\/blog-post\/%e3%8b%83%e3%8f%af-2026-1800-1900-am1480-25%e9%80%b1%e5%b9%b4%e5%8f%b0%e6%85%b6%e7%89%b9%e5%82%99%e7%af%80%e7%9b%ae%e3%80%8aclassic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c%e5%bb%bf\/\" rel=\"bookmark\">\u32c3\u33ef 2026 18:00-19:00 AM1480 25\u9031\u5e74\u53f0\u6176\u7279\u5099\u7bc0\u76ee\u300aClassic 25 \u2013 \u56de\u5473\u597d\u6b4c\u5eff\u4e94\u8f09&#128252;\u300bEP6 \u4e3b\u6301\uff1a\u6587\u6d69<\/a><\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"blog-content-excerpt\">\n\t\t\t\t\t\t\t<!-- wp:audio {\"id\":70510} -->\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/04\/2026.04.16-18.00.00-D.mp3\"><\/audio><\/figure>\n<!-- \/wp:audio -->\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div id=\"post-70318\" class=\"blog type-blog blog-clearfix wpbaw-blog-class blog-col-2 wpbaw-first has-no-date no-thumb\">\n\t\t\t<div class=\"blog-inner-wrap-view blog-clearfix\">\n\t\t\t\t\n\t\t\t\t<div class=\"blog-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"post-content-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"blog-title\"><a href=\"https:\/\/nysino.com\/am1480\/blog-post\/%e3%8b%83%e3%8f%a8-2026-1800-1900-am1480-25%e9%80%b1%e5%b9%b4%e5%8f%b0%e6%85%b6%e7%89%b9%e5%82%99%e7%af%80%e7%9b%ae%e3%80%8aclassic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c%e5%bb%bf\/\" rel=\"bookmark\">\u32c3\u33e8 2026 18:00-19:00 AM1480 25\u9031\u5e74\u53f0\u6176\u7279\u5099\u7bc0\u76ee\u300aClassic 25 \u2013 \u56de\u5473\u597d\u6b4c\u5eff\u4e94\u8f09&#128252;\u300bEP5 \u4e3b\u6301\uff1a\u6587\u6d69<\/a><\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"blog-content-excerpt\">\n\t\t\t\t\t\t\t<!-- wp:audio {\"id\":70319} -->\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/04\/2026.04.09-18.00.00-D.mp3\"><\/audio><\/figure>\n<!-- \/wp:audio -->\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div id=\"post-70272\" class=\"blog type-blog blog-clearfix wpbaw-blog-class blog-col-2 has-no-date no-thumb\">\n\t\t\t<div class=\"blog-inner-wrap-view blog-clearfix\">\n\t\t\t\t\n\t\t\t\t<div class=\"blog-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"post-content-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"blog-title\"><a href=\"https:\/\/nysino.com\/am1480\/blog-post\/%e3%8b%83%e3%8f%a1-2026-1800-1900-am1480-25%e9%80%b1%e5%b9%b4%e5%8f%b0%e6%85%b6%e7%89%b9%e5%82%99%e7%af%80%e7%9b%ae%e3%80%8aclassic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c%e5%bb%bf\/\" rel=\"bookmark\">\u32c3\u33e1 2026 18:00-19:00 AM1480 25\u9031\u5e74\u53f0\u6176\u7279\u5099\u7bc0\u76ee\u300aClassic 25 \u2013 \u56de\u5473\u597d\u6b4c\u5eff\u4e94\u8f09&#128252;\u300bEP4 \u4e3b\u6301\uff1a\u6587\u6d69<\/a><\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"blog-content-excerpt\">\n\t\t\t\t\t\t\t<!-- wp:audio {\"id\":70273} -->\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/04\/2026.04.02-18.00.00-D.mp3\"><\/audio><\/figure>\n<!-- \/wp:audio -->\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div id=\"post-70028\" class=\"blog type-blog blog-clearfix wpbaw-blog-class blog-col-2 wpbaw-first has-no-date no-thumb\">\n\t\t\t<div class=\"blog-inner-wrap-view blog-clearfix\">\n\t\t\t\t\n\t\t\t\t<div class=\"blog-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"post-content-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"blog-title\"><a href=\"https:\/\/nysino.com\/am1480\/blog-post\/%e3%8b%82%e3%8f%b9-2026-1800-1900-am1480-25%e9%80%b1%e5%b9%b4%e5%8f%b0%e6%85%b6%e7%89%b9%e5%82%99%e7%af%80%e7%9b%ae%e3%80%8aclassic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c%e5%bb%bf%e4%ba%94\/\" rel=\"bookmark\">\u32c2\u33f9 2026 18:00-19:00 AM1480 25\u9031\u5e74\u53f0\u6176\u7279\u5099\u7bc0\u76ee\u300aClassic 25 &#8211; \u56de\u5473\u597d\u6b4c\u5eff\u4e94\u8f09&#128252;\u300bEP3 \u4e3b\u6301\uff1a\u6587\u6d69<\/a><\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"blog-content-excerpt\">\n\t\t\t\t\t\t\t<!-- wp:audio {\"id\":70029} -->\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/2026.03.26-18.00.00-D.mp3\"><\/audio><\/figure>\n<!-- \/wp:audio -->\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div id=\"post-70026\" class=\"blog type-blog blog-clearfix wpbaw-blog-class blog-col-2 has-no-date no-thumb\">\n\t\t\t<div class=\"blog-inner-wrap-view blog-clearfix\">\n\t\t\t\t\n\t\t\t\t<div class=\"blog-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"post-content-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"blog-title\"><a href=\"https:\/\/nysino.com\/am1480\/blog-post\/%e3%8b%82%e3%8f%b2-2026-1800-1900-am1480-25%e9%80%b1%e5%b9%b4%e5%8f%b0%e6%85%b6%e7%89%b9%e5%82%99%e7%af%80%e7%9b%ae%e3%80%8aclassic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c%e5%bb%bf%e4%ba%94\/\" rel=\"bookmark\">\u32c2\u33f2 2026 18:00-19:00 AM1480 25\u9031\u5e74\u53f0\u6176\u7279\u5099\u7bc0\u76ee\u300aClassic 25 &#8211; \u56de\u5473\u597d\u6b4c\u5eff\u4e94\u8f09&#128252;\u300bEP2 \u4e3b\u6301\uff1a\u6587\u6d69<\/a><\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"blog-content-excerpt\">\n\t\t\t\t\t\t\t<!-- wp:audio {\"id\":70027} -->\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/2026.03.19-18.00.00-D.mp3\"><\/audio><\/figure>\n<!-- \/wp:audio -->\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div id=\"post-70024\" class=\"blog type-blog blog-clearfix wpbaw-blog-class blog-col-2 wpbaw-first has-no-date no-thumb\">\n\t\t\t<div class=\"blog-inner-wrap-view blog-clearfix\">\n\t\t\t\t\n\t\t\t\t<div class=\"blog-content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"post-content-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"blog-title\"><a href=\"https:\/\/nysino.com\/am1480\/blog-post\/%e3%8b%82%e3%8f%ab-2026-1800-1900-am1480-25%e9%80%b1%e5%b9%b4%e5%8f%b0%e6%85%b6%e7%89%b9%e5%82%99%e7%af%80%e7%9b%ae%e3%80%8aclassic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c%e5%bb%bf%e4%ba%94\/\" rel=\"bookmark\">\u32c2\u33eb 2026 18:00-19:00 AM1480 25\u9031\u5e74\u53f0\u6176\u7279\u5099\u7bc0\u76ee\u300aClassic 25 &#8211; \u56de\u5473\u597d\u6b4c\u5eff\u4e94\u8f09&#128252;\u300bEP1 \u4e3b\u6301\uff1a\u6587\u6d69<\/a><\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"blog-content-excerpt\">\n\t\t\t\t\t\t\t<!-- wp:audio {\"id\":70025} -->\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/2026.03.12-18.00.00-D.mp3\"><\/audio><\/figure>\n<!-- \/wp:audio -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":409,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Classic 25 \u56de\u5473\u597d\u6b4c25\u8f09 - AM1480<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nysino.com\/am1480\/\u7bc0\u76ee\u9304\u97f3\/classic-25-\u56de\u5473\u597d\u6b4c25\u8f09\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Classic 25 \u56de\u5473\u597d\u6b4c25\u8f09 - AM1480\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nysino.com\/am1480\/\u7bc0\u76ee\u9304\u97f3\/classic-25-\u56de\u5473\u597d\u6b4c25\u8f09\/\" \/>\n<meta property=\"og:site_name\" content=\"AM1480\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-22T15:37:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/Classic-25-\u56de\u5473\u597d\u6b4c25\u8f09-\u4e3b\u6301-\u6587\u6d69-1024x576.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/nysino.com\/am1480\/#organization\",\"name\":\"MRBI\",\"url\":\"https:\/\/nysino.com\/am1480\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/nysino.com\/am1480\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2023\/09\/MRBI_logo_grow_trans_284x1011.png\",\"contentUrl\":\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2023\/09\/MRBI_logo_grow_trans_284x1011.png\",\"width\":284,\"height\":101,\"caption\":\"MRBI\"},\"image\":{\"@id\":\"https:\/\/nysino.com\/am1480\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nysino.com\/am1480\/#website\",\"url\":\"https:\/\/nysino.com\/am1480\/\",\"name\":\"AM1480\",\"description\":\"WZRC AM1480 \\u7d10\\u7d04\\u83ef\\u8a9e\\u5ee3\\u64ad\\u96fb\\u53f0\",\"publisher\":{\"@id\":\"https:\/\/nysino.com\/am1480\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nysino.com\/am1480\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/Classic-25-\\u56de\\u5473\\u597d\\u6b4c25\\u8f09-\\u4e3b\\u6301-\\u6587\\u6d69.png\",\"contentUrl\":\"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/Classic-25-\\u56de\\u5473\\u597d\\u6b4c25\\u8f09-\\u4e3b\\u6301-\\u6587\\u6d69.png\",\"width\":1920,\"height\":1080},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/#webpage\",\"url\":\"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/\",\"name\":\"Classic 25 \\u56de\\u5473\\u597d\\u6b4c25\\u8f09 - AM1480\",\"isPartOf\":{\"@id\":\"https:\/\/nysino.com\/am1480\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/#primaryimage\"},\"datePublished\":\"2026-03-22T15:31:09+00:00\",\"dateModified\":\"2026-03-22T15:37:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\\u9996\\u9801\",\"item\":\"https:\/\/nysino.com\/am1480\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u7bc0\\u76ee\\u9304\\u97f3\",\"item\":\"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Classic 25 \\u56de\\u5473\\u597d\\u6b4c25\\u8f09\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Classic 25 \u56de\u5473\u597d\u6b4c25\u8f09 - AM1480","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nysino.com\/am1480\/\u7bc0\u76ee\u9304\u97f3\/classic-25-\u56de\u5473\u597d\u6b4c25\u8f09\/","og_locale":"en_US","og_type":"article","og_title":"Classic 25 \u56de\u5473\u597d\u6b4c25\u8f09 - AM1480","og_url":"https:\/\/nysino.com\/am1480\/\u7bc0\u76ee\u9304\u97f3\/classic-25-\u56de\u5473\u597d\u6b4c25\u8f09\/","og_site_name":"AM1480","article_modified_time":"2026-03-22T15:37:54+00:00","og_image":[{"url":"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/Classic-25-\u56de\u5473\u597d\u6b4c25\u8f09-\u4e3b\u6301-\u6587\u6d69-1024x576.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/nysino.com\/am1480\/#organization","name":"MRBI","url":"https:\/\/nysino.com\/am1480\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/nysino.com\/am1480\/#logo","inLanguage":"en-US","url":"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2023\/09\/MRBI_logo_grow_trans_284x1011.png","contentUrl":"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2023\/09\/MRBI_logo_grow_trans_284x1011.png","width":284,"height":101,"caption":"MRBI"},"image":{"@id":"https:\/\/nysino.com\/am1480\/#logo"}},{"@type":"WebSite","@id":"https:\/\/nysino.com\/am1480\/#website","url":"https:\/\/nysino.com\/am1480\/","name":"AM1480","description":"WZRC AM1480 \u7d10\u7d04\u83ef\u8a9e\u5ee3\u64ad\u96fb\u53f0","publisher":{"@id":"https:\/\/nysino.com\/am1480\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nysino.com\/am1480\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/#primaryimage","inLanguage":"en-US","url":"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/Classic-25-\u56de\u5473\u597d\u6b4c25\u8f09-\u4e3b\u6301-\u6587\u6d69.png","contentUrl":"https:\/\/nysino.com\/am1480\/wp-content\/uploads\/2026\/03\/Classic-25-\u56de\u5473\u597d\u6b4c25\u8f09-\u4e3b\u6301-\u6587\u6d69.png","width":1920,"height":1080},{"@type":"WebPage","@id":"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/#webpage","url":"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/","name":"Classic 25 \u56de\u5473\u597d\u6b4c25\u8f09 - AM1480","isPartOf":{"@id":"https:\/\/nysino.com\/am1480\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/#primaryimage"},"datePublished":"2026-03-22T15:31:09+00:00","dateModified":"2026-03-22T15:37:54+00:00","breadcrumb":{"@id":"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/classic-25-%e5%9b%9e%e5%91%b3%e5%a5%bd%e6%ad%8c25%e8%bc%89\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/nysino.com\/am1480\/"},{"@type":"ListItem","position":2,"name":"\u7bc0\u76ee\u9304\u97f3","item":"https:\/\/nysino.com\/am1480\/%e7%af%80%e7%9b%ae%e9%8c%84%e9%9f%b3\/"},{"@type":"ListItem","position":3,"name":"Classic 25 \u56de\u5473\u597d\u6b4c25\u8f09"}]}]}},"_links":{"self":[{"href":"https:\/\/nysino.com\/am1480\/wp-json\/wp\/v2\/pages\/69878"}],"collection":[{"href":"https:\/\/nysino.com\/am1480\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nysino.com\/am1480\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nysino.com\/am1480\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nysino.com\/am1480\/wp-json\/wp\/v2\/comments?post=69878"}],"version-history":[{"count":4,"href":"https:\/\/nysino.com\/am1480\/wp-json\/wp\/v2\/pages\/69878\/revisions"}],"predecessor-version":[{"id":69883,"href":"https:\/\/nysino.com\/am1480\/wp-json\/wp\/v2\/pages\/69878\/revisions\/69883"}],"up":[{"embeddable":true,"href":"https:\/\/nysino.com\/am1480\/wp-json\/wp\/v2\/pages\/409"}],"wp:attachment":[{"href":"https:\/\/nysino.com\/am1480\/wp-json\/wp\/v2\/media?parent=69878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nysino.com\/am1480\/wp-json\/wp\/v2\/categories?post=69878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nysino.com\/am1480\/wp-json\/wp\/v2\/tags?post=69878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}